{"id":4130,"date":"2020-03-06T17:24:24","date_gmt":"2020-03-06T16:24:24","guid":{"rendered":"http:\/\/videom.it\/blog\/?p=4130"},"modified":"2020-03-06T18:09:53","modified_gmt":"2020-03-06T17:09:53","slug":"nasce-windtre","status":"publish","type":"post","link":"https:\/\/videom.it\/blog\/nasce-windtre\/","title":{"rendered":"Nasce il nuovo Brand Windtre: addio a Wind e Tre"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/nuovo-logo-windtre-blog.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\" wp-image-4131 alignleft\" src=\"https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/nuovo-logo-windtre-blog-300x206.jpg?resize=233%2C160\" alt=\"nasce\" width=\"233\" height=\"160\" srcset=\"https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/nuovo-logo-windtre-blog.jpg?resize=300%2C206&amp;ssl=1 300w, https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/nuovo-logo-windtre-blog.jpg?resize=768%2C527&amp;ssl=1 768w, https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/nuovo-logo-windtre-blog.jpg?resize=100%2C69&amp;ssl=1 100w, https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/nuovo-logo-windtre-blog.jpg?resize=150%2C103&amp;ssl=1 150w, https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/nuovo-logo-windtre-blog.jpg?resize=200%2C137&amp;ssl=1 200w, https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/nuovo-logo-windtre-blog.jpg?resize=450%2C309&amp;ssl=1 450w, https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/nuovo-logo-windtre-blog.jpg?resize=600%2C412&amp;ssl=1 600w, https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/nuovo-logo-windtre-blog.jpg?w=839&amp;ssl=1 839w\" sizes=\"(max-width: 233px) 100vw, 233px\" \/><\/a>Dopo mesi di preparazione e riorganizzazione aziendale, da nasce e si parte per una nuova avventura nel mondo delle comunicazioni telefoniche.<\/p>\n<p>Nasce il nuovo marchio di<strong> <a href=\"http:\/\/videom.it\/blog\/wind-tre-brand\/\" target=\"_blank\" rel=\"noopener noreferrer\">WindTre<\/a><\/strong>, Il nuovo Brand frutto della fusione tra Wind e 3, che quindi ora si finalizza definitivamente.<\/p>\n<p>Il nuovo nome sostituisce i due marchi, per la rete fissa e mobile, le relative offerte. La novit\u00e0 si accompagna inoltre al completamento della rete unica. Forte di 20 mila siti e investimenti di 6 miliardi di euro previsti in cinque anni e riguarda circa 25 milioni di persone.\u00a0 Questo \u00e8 il numero di utenti fissi e mobili che sono a marchio Wind e 3.<br \/>\nTra gli effetti \u00e8 che adesso gli utenti sim Wind possono sfruttare anche quella che era la rete mobile di 3 e viceversa, con un miglioramento di copertura e prestazioni. Possibilit\u00e0 che nei mesi scorsi c&#8217;\u00e8 stata solo in un (progressivamente crescente) numero di citt\u00e0.<\/p>\n<p>La rete unica \u00e8 anche occasione per rilanciare sulla strategia <strong><a href=\"https:\/\/it.wikipedia.org\/wiki\/5G\" target=\"_blank\" rel=\"noopener noreferrer\">5G<\/a><\/strong>. L&#8217;operatore fa sapere che lancer\u00e0 il servizio 5G a luglio. Per Tim e Vodafone il debutto \u00e8 stato a met\u00e0 2019. La relativa rete si completer\u00e0 verso febbraio 2021.<br \/>\nIl lancio di WindTre in un unico nuovo marchio rappresenta una svolta decisiva per l&#8217;azienda, l&#8217;inizio di una nuova fase per i clienti consumer e business.<\/p>\n<p>Con il nuovo brand unico e l&#8217;infrastruttura mobile pi\u00f9 grande d&#8217;Italia, la Windtre affronter\u00e0 al meglio il futuro nel mondo delle telecomunicazioni.<\/p>\n<p>E allora, da giorno 16 Marzo 2016 si parte con il nuovo marchio e le nuove offerte per rafforzare la leadership di cui godono gi\u00e0 oggi Wind e Tre. Unito al nuovo Brand Very, si chiude il cerchio dell&#8217;azienda.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/02\/Logo-Very.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-medium wp-image-4105\" src=\"https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/02\/Logo-Very-300x137.jpg?resize=300%2C137\" alt=\"\" width=\"300\" height=\"137\" srcset=\"https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/02\/Logo-Very.jpg?resize=300%2C137&amp;ssl=1 300w, https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/02\/Logo-Very.jpg?resize=100%2C46&amp;ssl=1 100w, https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/02\/Logo-Very.jpg?resize=150%2C69&amp;ssl=1 150w, https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/02\/Logo-Very.jpg?resize=200%2C92&amp;ssl=1 200w, https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/02\/Logo-Very.jpg?w=332&amp;ssl=1 332w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Videomusic Trebisacce 26\/03\/2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo mesi di preparazione e riorganizzazione aziendale, da nasce e si parte per una nuova avventura nel mondo delle comunicazioni&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4136,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[34],"tags":[60,124,64],"class_list":["post-4130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-3ita","tag-news","tag-wind"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nasce il nuovo Brand Windtre: addio a Wind e Tre<\/title>\n<meta name=\"description\" content=\"Nasce il nuovo marchio di WindTre, l&#039;operatore frutto della fusione tra Wind e 3, che quindi ora si finalizza definitivamente. Il nuovo nome sostituisce...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/videom.it\/blog\/nasce-windtre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nasce il nuovo Brand Windtre: addio a Wind e Tre\" \/>\n<meta property=\"og:description\" content=\"Nasce il nuovo marchio di WindTre, l&#039;operatore frutto della fusione tra Wind e 3, che quindi ora si finalizza definitivamente. Il nuovo nome sostituisce...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/videom.it\/blog\/nasce-windtre\/\" \/>\n<meta property=\"og:site_name\" content=\"VideoMusic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/videomusiccava.trebisacce\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-06T16:24:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-06T17:09:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/windtrevmblog.jpg?fit=800%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VideoMusic-Cava\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"VideoMusic-Cava\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/\"},\"author\":{\"name\":\"VideoMusic-Cava\",\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/#\\\/schema\\\/person\\\/40ba89eef1c5f25d737fb3ef4f072a20\"},\"headline\":\"Nasce il nuovo Brand Windtre: addio a Wind e Tre\",\"datePublished\":\"2020-03-06T16:24:24+00:00\",\"dateModified\":\"2020-03-06T17:09:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/\"},\"wordCount\":279,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/videom.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/windtrevmblog.jpg?fit=800%2C800&ssl=1\",\"keywords\":[\"3Ita\",\"news\",\"Wind\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/\",\"url\":\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/\",\"name\":\"Nasce il nuovo Brand Windtre: addio a Wind e Tre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/videom.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/windtrevmblog.jpg?fit=800%2C800&ssl=1\",\"datePublished\":\"2020-03-06T16:24:24+00:00\",\"dateModified\":\"2020-03-06T17:09:53+00:00\",\"description\":\"Nasce il nuovo marchio di WindTre, l'operatore frutto della fusione tra Wind e 3, che quindi ora si finalizza definitivamente. Il nuovo nome sostituisce...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/videom.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/windtrevmblog.jpg?fit=800%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/videom.it\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/windtrevmblog.jpg?fit=800%2C800&ssl=1\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/nasce-windtre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/videom.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nasce il nuovo Brand Windtre: addio a Wind e Tre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/videom.it\\\/blog\\\/\",\"name\":\"VideoMusic\",\"description\":\"Luce &amp; Gas - Assicurazioni - Riparazioni\",\"publisher\":{\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/videom.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/#organization\",\"name\":\"VideoMusic\",\"url\":\"https:\\\/\\\/videom.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/videom.it\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/25th-giallo-3.jpg?fit=1300%2C1192&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/videom.it\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/25th-giallo-3.jpg?fit=1300%2C1192&ssl=1\",\"width\":1300,\"height\":1192,\"caption\":\"VideoMusic\"},\"image\":{\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/videomusiccava.trebisacce\",\"https:\\\/\\\/x.com\\\/vbcava\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgNxnZpk2zqHaIcIxF3swOA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/videom.it\\\/blog\\\/#\\\/schema\\\/person\\\/40ba89eef1c5f25d737fb3ef4f072a20\",\"name\":\"VideoMusic-Cava\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e327a76d3b7d6d9b7306f90ce5cde05948a3a95d325fe1ddd479ac1ea3d5982e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e327a76d3b7d6d9b7306f90ce5cde05948a3a95d325fe1ddd479ac1ea3d5982e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e327a76d3b7d6d9b7306f90ce5cde05948a3a95d325fe1ddd479ac1ea3d5982e?s=96&d=mm&r=g\",\"caption\":\"VideoMusic-Cava\"},\"sameAs\":[\"http:\\\/\\\/www.videom.it\"],\"url\":\"https:\\\/\\\/videom.it\\\/blog\\\/author\\\/videomusic-cava\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nasce il nuovo Brand Windtre: addio a Wind e Tre","description":"Nasce il nuovo marchio di WindTre, l'operatore frutto della fusione tra Wind e 3, che quindi ora si finalizza definitivamente. Il nuovo nome sostituisce...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/videom.it\/blog\/nasce-windtre\/","og_locale":"it_IT","og_type":"article","og_title":"Nasce il nuovo Brand Windtre: addio a Wind e Tre","og_description":"Nasce il nuovo marchio di WindTre, l'operatore frutto della fusione tra Wind e 3, che quindi ora si finalizza definitivamente. Il nuovo nome sostituisce...","og_url":"https:\/\/videom.it\/blog\/nasce-windtre\/","og_site_name":"VideoMusic","article_publisher":"https:\/\/www.facebook.com\/videomusiccava.trebisacce","article_published_time":"2020-03-06T16:24:24+00:00","article_modified_time":"2020-03-06T17:09:53+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/i1.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/windtrevmblog.jpg?fit=800%2C800&ssl=1","type":"image\/jpeg"}],"author":"VideoMusic-Cava","twitter_misc":{"Scritto da":"VideoMusic-Cava","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/videom.it\/blog\/nasce-windtre\/#article","isPartOf":{"@id":"https:\/\/videom.it\/blog\/nasce-windtre\/"},"author":{"name":"VideoMusic-Cava","@id":"https:\/\/videom.it\/blog\/#\/schema\/person\/40ba89eef1c5f25d737fb3ef4f072a20"},"headline":"Nasce il nuovo Brand Windtre: addio a Wind e Tre","datePublished":"2020-03-06T16:24:24+00:00","dateModified":"2020-03-06T17:09:53+00:00","mainEntityOfPage":{"@id":"https:\/\/videom.it\/blog\/nasce-windtre\/"},"wordCount":279,"commentCount":0,"publisher":{"@id":"https:\/\/videom.it\/blog\/#organization"},"image":{"@id":"https:\/\/videom.it\/blog\/nasce-windtre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/windtrevmblog.jpg?fit=800%2C800&ssl=1","keywords":["3Ita","news","Wind"],"articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/videom.it\/blog\/nasce-windtre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/videom.it\/blog\/nasce-windtre\/","url":"https:\/\/videom.it\/blog\/nasce-windtre\/","name":"Nasce il nuovo Brand Windtre: addio a Wind e Tre","isPartOf":{"@id":"https:\/\/videom.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/videom.it\/blog\/nasce-windtre\/#primaryimage"},"image":{"@id":"https:\/\/videom.it\/blog\/nasce-windtre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/windtrevmblog.jpg?fit=800%2C800&ssl=1","datePublished":"2020-03-06T16:24:24+00:00","dateModified":"2020-03-06T17:09:53+00:00","description":"Nasce il nuovo marchio di WindTre, l'operatore frutto della fusione tra Wind e 3, che quindi ora si finalizza definitivamente. Il nuovo nome sostituisce...","breadcrumb":{"@id":"https:\/\/videom.it\/blog\/nasce-windtre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/videom.it\/blog\/nasce-windtre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/videom.it\/blog\/nasce-windtre\/#primaryimage","url":"https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/windtrevmblog.jpg?fit=800%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/windtrevmblog.jpg?fit=800%2C800&ssl=1","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/videom.it\/blog\/nasce-windtre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/videom.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Nasce il nuovo Brand Windtre: addio a Wind e Tre"}]},{"@type":"WebSite","@id":"https:\/\/videom.it\/blog\/#website","url":"https:\/\/videom.it\/blog\/","name":"VideoMusic","description":"Luce &amp; Gas - Assicurazioni - Riparazioni","publisher":{"@id":"https:\/\/videom.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/videom.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/videom.it\/blog\/#organization","name":"VideoMusic","url":"https:\/\/videom.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/videom.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/videom.it\/blog\/wp-content\/uploads\/2015\/04\/25th-giallo-3.jpg?fit=1300%2C1192&ssl=1","contentUrl":"https:\/\/i2.wp.com\/videom.it\/blog\/wp-content\/uploads\/2015\/04\/25th-giallo-3.jpg?fit=1300%2C1192&ssl=1","width":1300,"height":1192,"caption":"VideoMusic"},"image":{"@id":"https:\/\/videom.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/videomusiccava.trebisacce","https:\/\/x.com\/vbcava","https:\/\/www.youtube.com\/channel\/UCgNxnZpk2zqHaIcIxF3swOA"]},{"@type":"Person","@id":"https:\/\/videom.it\/blog\/#\/schema\/person\/40ba89eef1c5f25d737fb3ef4f072a20","name":"VideoMusic-Cava","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e327a76d3b7d6d9b7306f90ce5cde05948a3a95d325fe1ddd479ac1ea3d5982e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e327a76d3b7d6d9b7306f90ce5cde05948a3a95d325fe1ddd479ac1ea3d5982e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e327a76d3b7d6d9b7306f90ce5cde05948a3a95d325fe1ddd479ac1ea3d5982e?s=96&d=mm&r=g","caption":"VideoMusic-Cava"},"sameAs":["http:\/\/www.videom.it"],"url":"https:\/\/videom.it\/blog\/author\/videomusic-cava\/"}]}},"views":2678,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/videom.it\/blog\/wp-content\/uploads\/2020\/03\/windtrevmblog.jpg?fit=800%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5ZUZm-14C","_links":{"self":[{"href":"https:\/\/videom.it\/blog\/wp-json\/wp\/v2\/posts\/4130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/videom.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/videom.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/videom.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/videom.it\/blog\/wp-json\/wp\/v2\/comments?post=4130"}],"version-history":[{"count":3,"href":"https:\/\/videom.it\/blog\/wp-json\/wp\/v2\/posts\/4130\/revisions"}],"predecessor-version":[{"id":4135,"href":"https:\/\/videom.it\/blog\/wp-json\/wp\/v2\/posts\/4130\/revisions\/4135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/videom.it\/blog\/wp-json\/wp\/v2\/media\/4136"}],"wp:attachment":[{"href":"https:\/\/videom.it\/blog\/wp-json\/wp\/v2\/media?parent=4130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/videom.it\/blog\/wp-json\/wp\/v2\/categories?post=4130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/videom.it\/blog\/wp-json\/wp\/v2\/tags?post=4130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}